{"id":1016,"date":"2021-02-06T14:13:38","date_gmt":"2021-02-06T13:13:38","guid":{"rendered":"https:\/\/news.vunderatert.lu\/?p=1016"},"modified":"2023-02-02T16:17:50","modified_gmt":"2023-02-02T15:17:50","slug":"compost-eco-habitat-partage","status":"publish","type":"post","link":"https:\/\/news.vunderatert.lu\/2021\/02\/compost-eco-habitat-partage\/","title":{"rendered":"Compost: eco-habitat partag\u00e9"},"content":{"rendered":"\n<p>La valorisation des restes de nos cultures sera am\u00e9lior\u00e9e pour les prochaines saisons. Nous voulons tirer meilleur parti de l&#8217;\u00e9nergie fix\u00e9e par la croissance des v\u00e9g\u00e9taux.<\/p>\n\n\n\n<p>Premier nouveau venu dans cette optique: un point compost bio. Les restes de culture y sont d\u00e9compos\u00e9s en douceur par champignons, insectes et limaces.<\/p>\n\n\n\n<p>Ces tas seront certainement aussi un lieu appr\u00e9ci\u00e9 des mulots, et peut \u00eatre aussi des chats&#8230; Un vrai HLM \u00e9cologique \ud83d\ude42<\/p>\n\n\n\n<p>Nous organiserons prochainement un atelier sur le sujet du compostage, bokashi et vermi-compost, autant de solutions possibles pour valoriser nos d\u00e9chets alimentaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La valorisation des restes de nos cultures sera am\u00e9lior\u00e9e pour les prochaines saisons. Nous voulons tirer meilleur parti de l&#8217;\u00e9nergie fix\u00e9e par la croissance des v\u00e9g\u00e9taux. Premier nouveau venu dans cette optique: un point compost bio. Les restes de culture y sont d\u00e9compos\u00e9s en douceur par champignons, insectes et limaces. Ces tas seront certainement aussi&hellip;&nbsp;<a href=\"https:\/\/news.vunderatert.lu\/2021\/02\/compost-eco-habitat-partage\/\" class=\"\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Compost: eco-habitat partag\u00e9<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"categories":[12],"tags":[18],"_links":{"self":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts\/1016"}],"collection":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":1,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts\/1016\/revisions"}],"predecessor-version":[{"id":1230,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts\/1016\/revisions\/1230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/media\/1021"}],"wp:attachment":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/categories?post=1016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/tags?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}