{"id":1025,"date":"2021-02-27T18:10:49","date_gmt":"2021-02-27T17:10:49","guid":{"rendered":"https:\/\/news.vunderatert.lu\/?p=1025"},"modified":"2023-02-02T16:18:16","modified_gmt":"2023-02-02T15:18:16","slug":"fleurs-a-couper-vun-der-atert","status":"publish","type":"post","link":"https:\/\/news.vunderatert.lu\/2021\/02\/fleurs-a-couper-vun-der-atert\/","title":{"rendered":"Fleurs \u00e0 couper Vun der Atert"},"content":{"rendered":"\n<p>Un nouveau projet prend vie autour du Gaart-\u00e0-Vous : Val\u00e9rie y pr\u00e9pare quelques \u00eelots de fleurs sauvages et \u00e0 couper pour composer vos bouquets.<\/p>\n\n\n\n<p>Nous appr\u00e9cions tous leurs couleurs \u00e9clatantes et leur parfums d\u00e9licats. Nous regrettons par contre que ce soit souvent au d\u00e9triment de notre sant\u00e9 et de l&#8217;air de nos int\u00e9rieurs, contamin\u00e9s par les pesticides, parfums artificiels et conservateurs utilis\u00e9s massivement dans la floristerie conventionnelle. Les fleurs bio sont vraiment rares \u00e0 Luxembourg.<\/p>\n\n\n\n<p>Alors nous souhaitons bienvenue et bon courage a Val\u00e9rie&#8230; et nous r\u00e9jouissons par avance de profiter, \u00e0 Beckerich, de couleurs chatoyantes estivales et automnales!<\/p>\n\n\n\n<p>Si vous souhaitez contribuer \u00e0 ce mini projet, ou d\u00e9velopper une autre id\u00e9e avec l&#8217;aide de la coop\u00e9rative n&#8217;h\u00e9sitez pas \u00e0 nous envoyer un email: koop@vunderatert.lu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nouveau projet prend vie autour du Gaart-\u00e0-Vous : Val\u00e9rie y pr\u00e9pare quelques \u00eelots de fleurs sauvages et \u00e0 couper pour composer vos bouquets. Nous appr\u00e9cions tous leurs couleurs \u00e9clatantes et leur parfums d\u00e9licats. Nous regrettons par contre que ce soit souvent au d\u00e9triment de notre sant\u00e9 et de l&#8217;air de nos int\u00e9rieurs, contamin\u00e9s par&hellip;&nbsp;<a href=\"https:\/\/news.vunderatert.lu\/2021\/02\/fleurs-a-couper-vun-der-atert\/\" class=\"\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Fleurs \u00e0 couper Vun der Atert<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"categories":[107,12],"tags":[109],"_links":{"self":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts\/1025"}],"collection":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/comments?post=1025"}],"version-history":[{"count":1,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts\/1025\/revisions"}],"predecessor-version":[{"id":1228,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/posts\/1025\/revisions\/1228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/media\/1024"}],"wp:attachment":[{"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/categories?post=1025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.vunderatert.lu\/wp-json\/wp\/v2\/tags?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}